{"id":16501,"date":"2020-11-19T20:47:32","date_gmt":"2020-11-19T23:47:32","guid":{"rendered":"https:\/\/radiosul.net\/wp\/?p=16501"},"modified":"2020-11-19T20:47:34","modified_gmt":"2020-11-19T23:47:34","slug":"farsul-recebe-visita-do-embaixador-dos-eua-no-brasil","status":"publish","type":"post","link":"https:\/\/radiosul.net\/wp\/2020\/farsul-recebe-visita-do-embaixador-dos-eua-no-brasil\/","title":{"rendered":"Farsul recebe visita do embaixador dos EUA no Brasil"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><em>Diplomata estava acompanhado do C\u00f4nsul Geral em Porto Alegre<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O embaixador dos EUA no Brasil, Todd Chapman, esteve na sede da Farsul nesta quinta-feira (19\/11). O diplomata estava acompanhado do c\u00f4nsul Geral dos EUA em Porto Alegre, Shane Christensen. Eles foram recebidos pelo presidente do Sistema Farsul, Gede\u00e3o Pereira, e por diretores da Federa\u00e7\u00e3o. O presidente da Fiergs, Gilberto Petry tamb\u00e9m participou do encontro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Na conversa foi tratada da produ\u00e7\u00e3o agropecu\u00e1ria de ambos os pa\u00edses, consolidados como maiores produtores de alimentos do mundo, e formas de fortalecer a parceria entre as duas na\u00e7\u00f5es. O economista-Chefe do Sistema Farsul, Ant\u00f4nio da Luz, fez uma apresenta\u00e7\u00e3o dos n\u00fameros do setor no Rio Grande do Sul.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tamb\u00e9m estavam presentes o diretor administrativo da Farsul, Francisco Schardong; o diretor financeiro da Farsul, Jos\u00e9 Alcindo \u00c1vila; o diretor e coordenador da Comiss\u00e3o do Meio Ambiente da Farsul, Domingos Lopes; o diretor vice-presidente da Farsul, F\u00e1bio Rodrigues; e o assessor da presid\u00eancia do Sistema Farsul, Luis Fernando Pires.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"312\" src=\"https:\/\/radiosul.net\/wp\/wp-content\/uploads\/2020\/11\/50621542131_c7377dcd32_z.jpg\" alt=\"\" class=\"wp-image-16502\" srcset=\"https:\/\/radiosul.net\/wp\/wp-content\/uploads\/2020\/11\/50621542131_c7377dcd32_z.jpg 640w, https:\/\/radiosul.net\/wp\/wp-content\/uploads\/2020\/11\/50621542131_c7377dcd32_z-300x146.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Fonte: Imprensa Sistema Farsul<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Diplomata estava acompanhado do C\u00f4nsul Geral em Porto Alegre O embaixador dos EUA no Brasil, Todd Chapman, esteve na sede da Farsul nesta quinta-feira (19\/11). O diplomata estava acompanhado do c\u00f4nsul Geral dos EUA em Porto Alegre, Shane Christensen. Eles foram recebidos pelo presidente do Sistema Farsul, Gede\u00e3o Pereira, e por diretores da Federa\u00e7\u00e3o. O &hellip;<\/p>\n","protected":false},"author":9,"featured_media":16497,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[1,126],"tags":[],"class_list":["post-16501","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agro","category-destacados"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Diplomata estava acompanhado do C\u00f4nsul Geral em Porto Alegre O embaixador dos EUA no Brasil, Todd Chapman, esteve na sede da Farsul nesta quinta-feira (19\/11). O diplomata estava acompanhado do c\u00f4nsul Geral dos EUA em Porto Alegre, Shane Christensen. Eles foram recebidos pelo presidente do Sistema Farsul, Gede\u00e3o Pereira, e por diretores da Federa\u00e7\u00e3o. O\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Alejo Bordon\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/radiosul.net\/wp\/2020\/farsul-recebe-visita-do-embaixador-dos-eua-no-brasil\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_BR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"radiosul.net - Regional por Excel\u00eancia\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Farsul recebe visita do embaixador dos EUA no Brasil - radiosul.net\" \/>\n\t\t<meta property=\"og:description\" content=\"Diplomata estava acompanhado do C\u00f4nsul Geral em Porto Alegre O embaixador dos EUA no Brasil, Todd Chapman, esteve na sede da Farsul nesta quinta-feira (19\/11). O diplomata estava acompanhado do c\u00f4nsul Geral dos EUA em Porto Alegre, Shane Christensen. Eles foram recebidos pelo presidente do Sistema Farsul, Gede\u00e3o Pereira, e por diretores da Federa\u00e7\u00e3o. O\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/radiosul.net\/wp\/2020\/farsul-recebe-visita-do-embaixador-dos-eua-no-brasil\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-11-19T23:47:32+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2020-11-19T23:47:34+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Farsul recebe visita do embaixador dos EUA no Brasil - radiosul.net\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Diplomata estava acompanhado do C\u00f4nsul Geral em Porto Alegre O embaixador dos EUA no Brasil, Todd Chapman, esteve na sede da Farsul nesta quinta-feira (19\/11). O diplomata estava acompanhado do c\u00f4nsul Geral dos EUA em Porto Alegre, Shane Christensen. Eles foram recebidos pelo presidente do Sistema Farsul, Gede\u00e3o Pereira, e por diretores da Federa\u00e7\u00e3o. O\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/radiosul.net\\\/wp\\\/2020\\\/farsul-recebe-visita-do-embaixador-dos-eua-no-brasil\\\/#blogposting\",\"name\":\"Farsul recebe visita do embaixador dos EUA no Brasil - radiosul.net\",\"headline\":\"Farsul recebe visita do embaixador dos EUA no Brasil\",\"author\":{\"@id\":\"https:\\\/\\\/radiosul.net\\\/wp\\\/author\\\/alejo\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/radiosul.net\\\/wp\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/radiosul.net\\\/wp\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/embaixada.jpg\",\"width\":600,\"height\":360,\"caption\":\"Foto - Gerson Raugust \\\/ Divulga\\u00e7\\u00e3o Sistema Farsul\"},\"datePublished\":\"2020-11-19T20:47:32-03:00\",\"dateModified\":\"2020-11-19T20:47:34-03:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/radiosul.net\\\/wp\\\/2020\\\/farsul-recebe-visita-do-embaixador-dos-eua-no-brasil\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/radiosul.net\\\/wp\\\/2020\\\/farsul-recebe-visita-do-embaixador-dos-eua-no-brasil\\\/#webpage\"},\"articleSection\":\"Agroneg\\u00f3cio, Destaque\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/radiosul.net\\\/wp\\\/2020\\\/farsul-recebe-visita-do-embaixador-dos-eua-no-brasil\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/radiosul.net\\\/wp#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/radiosul.net\\\/wp\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/radiosul.net\\\/wp\\\/category\\\/agro\\\/#listItem\",\"name\":\"Agroneg\\u00f3cio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/radiosul.net\\\/wp\\\/category\\\/agro\\\/#listItem\",\"position\":2,\"name\":\"Agroneg\\u00f3cio\",\"item\":\"https:\\\/\\\/radiosul.net\\\/wp\\\/category\\\/agro\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/radiosul.net\\\/wp\\\/2020\\\/farsul-recebe-visita-do-embaixador-dos-eua-no-brasil\\\/#listItem\",\"name\":\"Farsul recebe visita do embaixador dos EUA no Brasil\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/radiosul.net\\\/wp#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/radiosul.net\\\/wp\\\/2020\\\/farsul-recebe-visita-do-embaixador-dos-eua-no-brasil\\\/#listItem\",\"position\":3,\"name\":\"Farsul recebe visita do embaixador dos EUA no Brasil\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/radiosul.net\\\/wp\\\/category\\\/agro\\\/#listItem\",\"name\":\"Agroneg\\u00f3cio\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/radiosul.net\\\/wp\\\/#organization\",\"name\":\"radiosul.net\",\"description\":\"Regional por Excel\\u00eancia\",\"url\":\"https:\\\/\\\/radiosul.net\\\/wp\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/radiosul.net\\\/wp\\\/author\\\/alejo\\\/#author\",\"url\":\"https:\\\/\\\/radiosul.net\\\/wp\\\/author\\\/alejo\\\/\",\"name\":\"Alejo Bordon\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/radiosul.net\\\/wp\\\/2020\\\/farsul-recebe-visita-do-embaixador-dos-eua-no-brasil\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b3a7e7f1c71212e6a5b7183b79a2ab58dad8bdc4cd4eadd61c4434d010d0bae4?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Alejo Bordon\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/radiosul.net\\\/wp\\\/2020\\\/farsul-recebe-visita-do-embaixador-dos-eua-no-brasil\\\/#webpage\",\"url\":\"https:\\\/\\\/radiosul.net\\\/wp\\\/2020\\\/farsul-recebe-visita-do-embaixador-dos-eua-no-brasil\\\/\",\"name\":\"Farsul recebe visita do embaixador dos EUA no Brasil - radiosul.net\",\"description\":\"Diplomata estava acompanhado do C\\u00f4nsul Geral em Porto Alegre O embaixador dos EUA no Brasil, Todd Chapman, esteve na sede da Farsul nesta quinta-feira (19\\\/11). O diplomata estava acompanhado do c\\u00f4nsul Geral dos EUA em Porto Alegre, Shane Christensen. Eles foram recebidos pelo presidente do Sistema Farsul, Gede\\u00e3o Pereira, e por diretores da Federa\\u00e7\\u00e3o. O\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radiosul.net\\\/wp\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/radiosul.net\\\/wp\\\/2020\\\/farsul-recebe-visita-do-embaixador-dos-eua-no-brasil\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/radiosul.net\\\/wp\\\/author\\\/alejo\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/radiosul.net\\\/wp\\\/author\\\/alejo\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/radiosul.net\\\/wp\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/embaixada.jpg\",\"@id\":\"https:\\\/\\\/radiosul.net\\\/wp\\\/2020\\\/farsul-recebe-visita-do-embaixador-dos-eua-no-brasil\\\/#mainImage\",\"width\":600,\"height\":360,\"caption\":\"Foto - Gerson Raugust \\\/ Divulga\\u00e7\\u00e3o Sistema Farsul\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/radiosul.net\\\/wp\\\/2020\\\/farsul-recebe-visita-do-embaixador-dos-eua-no-brasil\\\/#mainImage\"},\"datePublished\":\"2020-11-19T20:47:32-03:00\",\"dateModified\":\"2020-11-19T20:47:34-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/radiosul.net\\\/wp\\\/#website\",\"url\":\"https:\\\/\\\/radiosul.net\\\/wp\\\/\",\"name\":\"radiosul.net\",\"description\":\"Regional por Excel\\u00eancia\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/radiosul.net\\\/wp\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Farsul recebe visita do embaixador dos EUA no Brasil - radiosul.net","description":"Diplomata estava acompanhado do C\u00f4nsul Geral em Porto Alegre O embaixador dos EUA no Brasil, Todd Chapman, esteve na sede da Farsul nesta quinta-feira (19\/11). O diplomata estava acompanhado do c\u00f4nsul Geral dos EUA em Porto Alegre, Shane Christensen. Eles foram recebidos pelo presidente do Sistema Farsul, Gede\u00e3o Pereira, e por diretores da Federa\u00e7\u00e3o. O","canonical_url":"https:\/\/radiosul.net\/wp\/2020\/farsul-recebe-visita-do-embaixador-dos-eua-no-brasil\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/radiosul.net\/wp\/2020\/farsul-recebe-visita-do-embaixador-dos-eua-no-brasil\/#blogposting","name":"Farsul recebe visita do embaixador dos EUA no Brasil - radiosul.net","headline":"Farsul recebe visita do embaixador dos EUA no Brasil","author":{"@id":"https:\/\/radiosul.net\/wp\/author\/alejo\/#author"},"publisher":{"@id":"https:\/\/radiosul.net\/wp\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/radiosul.net\/wp\/wp-content\/uploads\/2020\/11\/embaixada.jpg","width":600,"height":360,"caption":"Foto - Gerson Raugust \/ Divulga\u00e7\u00e3o Sistema Farsul"},"datePublished":"2020-11-19T20:47:32-03:00","dateModified":"2020-11-19T20:47:34-03:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/radiosul.net\/wp\/2020\/farsul-recebe-visita-do-embaixador-dos-eua-no-brasil\/#webpage"},"isPartOf":{"@id":"https:\/\/radiosul.net\/wp\/2020\/farsul-recebe-visita-do-embaixador-dos-eua-no-brasil\/#webpage"},"articleSection":"Agroneg\u00f3cio, Destaque"},{"@type":"BreadcrumbList","@id":"https:\/\/radiosul.net\/wp\/2020\/farsul-recebe-visita-do-embaixador-dos-eua-no-brasil\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/radiosul.net\/wp#listItem","position":1,"name":"Home","item":"https:\/\/radiosul.net\/wp","nextItem":{"@type":"ListItem","@id":"https:\/\/radiosul.net\/wp\/category\/agro\/#listItem","name":"Agroneg\u00f3cio"}},{"@type":"ListItem","@id":"https:\/\/radiosul.net\/wp\/category\/agro\/#listItem","position":2,"name":"Agroneg\u00f3cio","item":"https:\/\/radiosul.net\/wp\/category\/agro\/","nextItem":{"@type":"ListItem","@id":"https:\/\/radiosul.net\/wp\/2020\/farsul-recebe-visita-do-embaixador-dos-eua-no-brasil\/#listItem","name":"Farsul recebe visita do embaixador dos EUA no Brasil"},"previousItem":{"@type":"ListItem","@id":"https:\/\/radiosul.net\/wp#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/radiosul.net\/wp\/2020\/farsul-recebe-visita-do-embaixador-dos-eua-no-brasil\/#listItem","position":3,"name":"Farsul recebe visita do embaixador dos EUA no Brasil","previousItem":{"@type":"ListItem","@id":"https:\/\/radiosul.net\/wp\/category\/agro\/#listItem","name":"Agroneg\u00f3cio"}}]},{"@type":"Organization","@id":"https:\/\/radiosul.net\/wp\/#organization","name":"radiosul.net","description":"Regional por Excel\u00eancia","url":"https:\/\/radiosul.net\/wp\/"},{"@type":"Person","@id":"https:\/\/radiosul.net\/wp\/author\/alejo\/#author","url":"https:\/\/radiosul.net\/wp\/author\/alejo\/","name":"Alejo Bordon","image":{"@type":"ImageObject","@id":"https:\/\/radiosul.net\/wp\/2020\/farsul-recebe-visita-do-embaixador-dos-eua-no-brasil\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/b3a7e7f1c71212e6a5b7183b79a2ab58dad8bdc4cd4eadd61c4434d010d0bae4?s=96&d=mm&r=g","width":96,"height":96,"caption":"Alejo Bordon"}},{"@type":"WebPage","@id":"https:\/\/radiosul.net\/wp\/2020\/farsul-recebe-visita-do-embaixador-dos-eua-no-brasil\/#webpage","url":"https:\/\/radiosul.net\/wp\/2020\/farsul-recebe-visita-do-embaixador-dos-eua-no-brasil\/","name":"Farsul recebe visita do embaixador dos EUA no Brasil - radiosul.net","description":"Diplomata estava acompanhado do C\u00f4nsul Geral em Porto Alegre O embaixador dos EUA no Brasil, Todd Chapman, esteve na sede da Farsul nesta quinta-feira (19\/11). O diplomata estava acompanhado do c\u00f4nsul Geral dos EUA em Porto Alegre, Shane Christensen. Eles foram recebidos pelo presidente do Sistema Farsul, Gede\u00e3o Pereira, e por diretores da Federa\u00e7\u00e3o. O","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/radiosul.net\/wp\/#website"},"breadcrumb":{"@id":"https:\/\/radiosul.net\/wp\/2020\/farsul-recebe-visita-do-embaixador-dos-eua-no-brasil\/#breadcrumblist"},"author":{"@id":"https:\/\/radiosul.net\/wp\/author\/alejo\/#author"},"creator":{"@id":"https:\/\/radiosul.net\/wp\/author\/alejo\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/radiosul.net\/wp\/wp-content\/uploads\/2020\/11\/embaixada.jpg","@id":"https:\/\/radiosul.net\/wp\/2020\/farsul-recebe-visita-do-embaixador-dos-eua-no-brasil\/#mainImage","width":600,"height":360,"caption":"Foto - Gerson Raugust \/ Divulga\u00e7\u00e3o Sistema Farsul"},"primaryImageOfPage":{"@id":"https:\/\/radiosul.net\/wp\/2020\/farsul-recebe-visita-do-embaixador-dos-eua-no-brasil\/#mainImage"},"datePublished":"2020-11-19T20:47:32-03:00","dateModified":"2020-11-19T20:47:34-03:00"},{"@type":"WebSite","@id":"https:\/\/radiosul.net\/wp\/#website","url":"https:\/\/radiosul.net\/wp\/","name":"radiosul.net","description":"Regional por Excel\u00eancia","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/radiosul.net\/wp\/#organization"}}]},"og:locale":"pt_BR","og:site_name":"radiosul.net - Regional por Excel\u00eancia","og:type":"article","og:title":"Farsul recebe visita do embaixador dos EUA no Brasil - radiosul.net","og:description":"Diplomata estava acompanhado do C\u00f4nsul Geral em Porto Alegre O embaixador dos EUA no Brasil, Todd Chapman, esteve na sede da Farsul nesta quinta-feira (19\/11). O diplomata estava acompanhado do c\u00f4nsul Geral dos EUA em Porto Alegre, Shane Christensen. Eles foram recebidos pelo presidente do Sistema Farsul, Gede\u00e3o Pereira, e por diretores da Federa\u00e7\u00e3o. O","og:url":"https:\/\/radiosul.net\/wp\/2020\/farsul-recebe-visita-do-embaixador-dos-eua-no-brasil\/","article:published_time":"2020-11-19T23:47:32+00:00","article:modified_time":"2020-11-19T23:47:34+00:00","twitter:card":"summary_large_image","twitter:title":"Farsul recebe visita do embaixador dos EUA no Brasil - radiosul.net","twitter:description":"Diplomata estava acompanhado do C\u00f4nsul Geral em Porto Alegre O embaixador dos EUA no Brasil, Todd Chapman, esteve na sede da Farsul nesta quinta-feira (19\/11). O diplomata estava acompanhado do c\u00f4nsul Geral dos EUA em Porto Alegre, Shane Christensen. Eles foram recebidos pelo presidente do Sistema Farsul, Gede\u00e3o Pereira, e por diretores da Federa\u00e7\u00e3o. O"},"aioseo_meta_data":{"post_id":"16501","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2026-01-09 00:14:30","updated":"2026-01-09 00:14:30","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/radiosul.net\/wp\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/radiosul.net\/wp\/category\/agro\/\" title=\"Agroneg\u00f3cio\">Agroneg\u00f3cio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tFarsul recebe visita do embaixador dos EUA no Brasil\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/radiosul.net\/wp"},{"label":"Agroneg\u00f3cio","link":"https:\/\/radiosul.net\/wp\/category\/agro\/"},{"label":"Farsul recebe visita do embaixador dos EUA no Brasil","link":"https:\/\/radiosul.net\/wp\/2020\/farsul-recebe-visita-do-embaixador-dos-eua-no-brasil\/"}],"_links":{"self":[{"href":"https:\/\/radiosul.net\/wp\/wp-json\/wp\/v2\/posts\/16501","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiosul.net\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiosul.net\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiosul.net\/wp\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/radiosul.net\/wp\/wp-json\/wp\/v2\/comments?post=16501"}],"version-history":[{"count":1,"href":"https:\/\/radiosul.net\/wp\/wp-json\/wp\/v2\/posts\/16501\/revisions"}],"predecessor-version":[{"id":16503,"href":"https:\/\/radiosul.net\/wp\/wp-json\/wp\/v2\/posts\/16501\/revisions\/16503"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiosul.net\/wp\/wp-json\/wp\/v2\/media\/16497"}],"wp:attachment":[{"href":"https:\/\/radiosul.net\/wp\/wp-json\/wp\/v2\/media?parent=16501"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiosul.net\/wp\/wp-json\/wp\/v2\/categories?post=16501"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiosul.net\/wp\/wp-json\/wp\/v2\/tags?post=16501"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}